{"id":43783,"date":"2026-01-13T21:11:39","date_gmt":"2026-01-13T19:11:39","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/veranstaltungen\/ich-sehe-was-was-du-nicht-siehst\/"},"modified":"2026-01-13T21:11:39","modified_gmt":"2026-01-13T19:11:39","slug":"ich-sehe-was-was-du-nicht-siehst","status":"publish","type":"veranstaltungen","link":"https:\/\/stage.hannover-living.dev\/bg\/veranstaltungen\/ich-sehe-was-was-du-nicht-siehst\/","title":{"rendered":"Ich sehe was, was du nicht siehst!"},"author":0,"template":"","meta":{"ev_date":{"rrule":"DTSTART=19700101T000000Z","dates":[]},"ev_beschreibung":"<p class=\"western\"><span style=\"font-size: 9.0pt\">Wer bestimmt unsere Freiheit?<br \/>\nWer schreibt die Regeln, nach denen wir leben?<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 9.0pt\">Mit scharfem Blick und anarchischer Energie erz\u00e4hlt Ulli Lust vom Menschsein in all seinen widerspr\u00fcchlichen Facetten. Ihre Arbeiten sind radikal ehrlich, selbstironisch und zutiefst solidarisch, dabei aber unbequem, ber\u00fchrend und befreiend zugleich.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 9.0pt\">Die Ausstellung zeigt zentrale Werke aus ihren autobiografischen Comicromanen <em><span>Heute ist der letzte Tag vom Rest deines Lebens<\/span><\/em> und <em><span>Wie ich versuchte ein guter Mensch zu sein<\/span><\/em>. Sie erz\u00e4hlen von Freiheit und Weiblichkeit, aber auch von Tabus und Scham. Ulli Lust stellt sich selbst ins Zentrum, beobachtet statt zu erkl\u00e4ren \u2013 und h\u00e4lt uns dabei den Spiegel vor.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 9.0pt\">Mit ihrem mit dem Deutschen Sachbuchpreis ausgezeichneten Comic-Essay <em><span>Die Frau als Mensch<\/span><\/em> r\u00e4umt Lust zudem mit hartn\u00e4ckigen Mythen \u00fcber Geschlechterrollen in der Fr\u00fchgeschichte auf.\u00a0Erg\u00e4nzt durch Portr\u00e4ts, Reportagen und zeichnerische Beobachtungen entsteht ein vielstimmiges Panorama menschlicher Erfahrungen.<\/span><\/p>\n","ev_galerie":[],"ev_ticket":"","ev_poster":"","ev_veranstaltungsheader":"43784","ev_youtube":"","ev_kategorie":["kunst_kultur"],"ev_teaserbild":"43784","ev_teasertext":"Ulli Lust","ev_seo_name":"Karikaturmuseum Wilhelm Busch","ev_seo_strasse":"Georgengarten 1","ev_seo_plz":"30167","ev_seo_ort":"Hannover"},"class_list":["post-43783","veranstaltungen","type-veranstaltungen","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/bg\/wp-json\/wp\/v2\/veranstaltungen\/43783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/bg\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/bg\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/bg\/wp-json\/wp\/v2\/media?parent=43783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}