{"id":40930,"date":"2025-07-04T12:15:57","date_gmt":"2025-07-04T10:15:57","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/location\/kindermuseum-zinnober-interaktives-lernen-auf-800-m%c2%b2-in-hannover\/"},"modified":"2026-04-16T15:12:48","modified_gmt":"2026-04-16T13:12:48","slug":"kindermuseum-zinnober-interaktives-lernen-auf-800-m%c2%b2-in-hannover","status":"publish","type":"location","link":"https:\/\/stage.hannover-living.dev\/en\/location\/kindermuseum-zinnober-interaktives-lernen-auf-800-m%c2%b2-in-hannover\/","title":{"rendered":"Zinnober children's museum - interactive learning on 800 m\u00b2 in Hanover"},"template":"","meta":{"loc_subtitle":"Wir bieten einen kreativen Lernraum auch f\u00fcr Entdeckerinnen.","loc_beschreibung":"<p>Das <strong data-start=\"237\" data-end=\"262\">Zinnober Kindermuseum<\/strong> in Hannover bietet in gro\u00dfz\u00fcgigen R\u00e4umen auf zwei Etagen interaktive Ausstellungen und kreative Workshops f\u00fcr Kinder zwischen drei und 13 Jahren. Seit Januar 2022 befindet sich das Museum in neuen R\u00e4umlichkeiten am Lindener Berg und l\u00e4dt Familien, Schulklassen sowie Kindergruppen zum Mitmachen ein.<\/p>\n<h3 data-start=\"537\" data-end=\"568\">Ein Museum zum Anfassen<\/h3>\n<p>Das Kindermuseum Zinnober bietet wechselnde Mitmach-Ausstellungen zu Themen, die Kinder interessieren. Es geht um Wissenschaft, Kunst, Musik und Alltagswelten. Die Erlebnisstationen laden zum Experimentieren, Erforschen und Ausprobieren ein. Inhalte werden mit verschiedenen Sinnen im wahrsten Sinne des Wortes be-greiflich. Eine offenes Atelier und eine Forschwerkstatt f\u00f6rdern zus\u00e4tzlich die Kreativit\u00e4t der jungen Besucher*innen.<\/p>\n","loc_strasse":"Am Steinbruch ","loc_hausnummer":"16","loc_plz":"30449","loc_ort":"Hannover","loc_google_maps":"Am Steinbruch 16, 30449 Hannover, Deutschland","loc_telefonnummer":"","loc_stadtteil":"linden-mitte","loc_teaserbild":"43883","loc_teasertext":"Entdeckt interaktive Ausstellungen und kreative Workshops im Zinnober Kindermuseum Hannover.","loc_webseite":"https:\/\/www.kindermuseum-hannover.de\/","loc_360_link":"","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"true","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"false","loc_switch_open_show":"true","loc_open_montag":"Geschlossen","loc_open_dienstag":"09:00\u201317:00 Uhr","loc_open_mittwoch":"09:00\u201314:00 Uhr","loc_open_donnerstag":"09:00\u201317:00 Uhr","loc_open_freitag":"09:00\u201317:00 Uhr","loc_open_samstag":"10:00\u201317:00 Uhr","loc_open_sontag":"10:00\u201317:00 Uhr","loc_nachhaltigkeit":"false","loc_galerie":["Array"],"loc_location_art":["museen_galerien_kunstvereien"],"loc_nightlife":[],"loc_freizeit":["museen_galerien","spiel_spass","indoor"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Kindermuseum Zinnober - Interaktives Lernen auf 800\u202fm\u00b2 in Hannover,Am Steinbruch  1+,30449 Hannover","loc_admin_google_place_id":"ChIJk7e11_N0sEcRWh3ZiwOVQfI","loc_admin_master_id":"4173"},"class_list":["post-40930","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/location\/40930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/media?parent=40930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}