{"id":43763,"date":"2026-01-05T21:18:37","date_gmt":"2026-01-05T19:18:37","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/veranstaltungen\/tjark-2\/"},"modified":"2026-01-05T21:18:37","modified_gmt":"2026-01-05T19:18:37","slug":"tjark-2","status":"publish","type":"veranstaltungen","link":"https:\/\/stage.hannover-living.dev\/en\/veranstaltungen\/tjark-2\/","title":{"rendered":"Tjark"},"author":0,"template":"","meta":{"ev_date":{"rrule":"DTSTART=19700101T000000Z","dates":[{"start":"1788289200"}]},"ev_beschreibung":"<p>\u201eauch wenn\u2019s uns morgen nicht mehr gibt\u201c: mit diesem r\u00e4tselhaften Titel k\u00fcndigt TJARK sein Deb\u00fctalbum an \u2013 und macht damit einen Punkt hinter das erste, aufregende Kapitel seiner jungen Karriere. Hinter dem 21-j\u00e4hrigen Newcomer liegen beachtliche Meilensteine: millionenfach gestreamte Songs, eine erste eigene EP und schon zwei Live-Touren, auf denen er seine ber\u00fchrende Musik zwischen Indie-Pop, Folk und urbanen Sounds in ganz Deutschland auf die B\u00fchne gebracht hat. Nun ist TJARK bereit f\u00fcr die n\u00e4chste Etappe. Eine, in der er sich frei macht von den Erwartungen anderer, aber auch seinen eigenen. Eine, in der er die Gro\u00dfstadt hinter sich l\u00e4sst und gegen das beschauliche Dorfleben in seiner alten Heimat eintauscht. Statt sich jeden Abend der Hamburger Kiezkultur hinzugeben, genie\u00dft TJARK jetzt wieder die Ruhe und Idylle der Brandenburger Provinz \u2013 und hat durch diesen vermeintlichen Schritt zur\u00fcck zwei nach vorne gemacht. <em>\u201e2024 haben wir super viele Festivals und Support-Shows gespielt. Deshalb habe ich mich Anfang des Jahres dazu entschieden, wieder nach Hause zu ziehen, um mehr Ruhe zu haben und das war ein sehr wichtiger Schritt. Die meisten Songs wurden hier geschrieben und produziert, viele auch mit guten Freunden von mir und diese Umgebung hat einen gro\u00dfen Einfluss auf das Album gehabt\u201c<\/em>.<\/p>\n","ev_galerie":[],"ev_ticket":"https:\/\/www.eventim.de\/event\/tjark-auch-wenns-uns-morgen-nicht-mehr-gibt-tour-2026-kultur-und-kommunikationszentrum-pavillon-20751028\/?affiliate=ACK","ev_poster":"","ev_veranstaltungsheader":"43764","ev_youtube":"","ev_kategorie":["musik_konzerte"],"ev_teaserbild":"43764","ev_teasertext":"auch wenn's uns morgen nicht mehr gibt Tour 2026","ev_seo_name":"Pavillon","ev_seo_strasse":"Lister Meile 4","ev_seo_plz":"30161","ev_seo_ort":"Hannover"},"class_list":["post-43763","veranstaltungen","type-veranstaltungen","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/veranstaltungen\/43763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/en\/wp-json\/wp\/v2\/media?parent=43763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}