{"id":34258,"date":"2025-04-28T12:49:53","date_gmt":"2025-04-28T10:49:53","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/location\/christuskirche\/"},"modified":"2025-08-29T15:21:41","modified_gmt":"2025-08-29T13:21:41","slug":"christuskirche","status":"publish","type":"location","link":"https:\/\/stage.hannover-living.dev\/es\/location\/christuskirche\/","title":{"rendered":"Iglesia de Cristo"},"template":"","meta":{"loc_subtitle":"Neugotisches Meisterwerk und internationales Chorzentrum","loc_beschreibung":"<p>Die Christuskirche Hannover im Stadtteil Nordstadt ist ein herausragendes Beispiel neugotischer Kirchenarchitektur und dient heute als internationales Zentrum f\u00fcr Chormusik. Urspr\u00fcnglich zwischen 1859 und 1864 als Residenzkirche f\u00fcr K\u00f6nig Georg V. von Hannover nach den Pl\u00e4nen des Architekten Conrad Wilhelm Hase erbaut, wurde sie nur einmal, am Tag ihrer Einweihung, als solche genutzt. Heute ist die Kirche ein bedeutendes kulturelles Zentrum.<\/p>\n<h2>Architektonische Besonderheiten<\/h2>\n<p>Die Christuskirche beeindruckt durch ihre neugotische Bauweise mit einem 70 Meter hohen Turm, der in das Mittelschiff integriert ist \u2013 eine architektonische Besonderheit, die durch die begrenzte Ost-West-Ausdehnung des Bauplatzes bedingt war. Die Westfassade ist in Anlehnung an den Freiburger und Stra\u00dfburger M\u00fcnster gestaltet und zeichnet sich durch filigrane Sandsteinornamente, Fialen und Wasserspeier aus. Im Inneren der Kirche befindet sich eine Orgel mit 55 Registern, die 1958 von Orgelbaumeister Hillebrand erbaut wurde.<\/p>\n<h2>Geschichte und Wiederaufbau<\/h2>\n<p>W\u00e4hrend des Zweiten Weltkriegs wurde die Christuskirche schwer besch\u00e4digt. Der Wiederaufbau begann 1951, und bereits 1953 konnte wieder ein Gottesdienst stattfinden. Im Jahr 2013 wurde die Kirche umfassend renoviert und zum Internationalen Kinder- und Jugendchorzentrum umgestaltet. Dabei wurde das alte Kirchengest\u00fchl entfernt und durch einen ansteigenden Probenraum ersetzt. Die Hillebrand-Orgel wurde ausgebaut und eingelagert, das Deckengew\u00f6lbe saniert und mit neuem Sternenschmuck versehen.<\/p>\n<h2>Heutige Nutzung<\/h2>\n<p>Heute ist die Christuskirche Sitz des Internationalen Chorzentrum Hannover und Heimat des M\u00e4dchenchors Hannover. Die Kirche dient als Proben- und Auff\u00fchrungsort f\u00fcr Ch\u00f6re aus aller Welt und bleibt gleichzeitig ein Ort f\u00fcr Gottesdienste und kulturelle Veranstaltungen.<\/p>\n","loc_strasse":"An d. Christuskirche","loc_hausnummer":"1","loc_plz":"30167","loc_ort":"Nordstadt","loc_google_maps":"Christuskirche,An d. Christuskirche , 30167 Nordstadt","loc_telefonnummer":"","loc_stadtteil":"nordstadt","loc_teaserbild":"41704","loc_teasertext":"Die Christuskirche Hannover beeindruckt mit neugotischer Architektur und ist heute ein internationales Zentrum f\u00fcr Chormusik.","loc_webseite":"https:\/\/www.christuskirche-hannover.de\/","loc_360_link":"https:\/\/360.hannover-living.de\/wp-content\/uploads\/panorama\/RundgangKirchenKK.html","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"true","loc_switch_open_show":"true","loc_open_montag":"","loc_open_dienstag":"","loc_open_mittwoch":"","loc_open_donnerstag":"","loc_open_freitag":"","loc_open_samstag":"","loc_open_sontag":"","loc_nachhaltigkeit":"false","loc_galerie":["41704"],"loc_location_art":["sightseeing"],"loc_nightlife":[],"loc_freizeit":["sehenswuerdigkeiten_highlights"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Christuskirche,An d. Christuskirche 1,30167 Nordstadt","loc_admin_google_place_id":"ChIJu0Vra6J0sEcR0dHp0rHL0RQ","loc_admin_master_id":"845"},"class_list":["post-34258","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/es\/wp-json\/wp\/v2\/location\/34258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/es\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/es\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/es\/wp-json\/wp\/v2\/media?parent=34258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}