{"id":35944,"date":"2025-05-01T13:43:08","date_gmt":"2025-05-01T11:43:08","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/stadtteil\/gross-buchholz\/"},"modified":"2025-08-12T15:50:55","modified_gmt":"2025-08-12T13:50:55","slug":"gross-buchholz","status":"publish","type":"stadtteil","link":"https:\/\/stage.hannover-living.dev\/it\/stadtteil\/gross-buchholz\/","title":{"rendered":"Gro\u00df-Buchholz"},"template":"","meta":{"dis_headerimage":"https:\/\/stage.hannover-living.dev\/wp-content\/uploads\/2025\/05\/Design-ohne-Titel167.png","dis_beschreibung":"Willkommen im Stadtteil Gro\u00df-Buchholz!\r\nIm Nordosten Hannovers gelegen, verbindet Gro\u00df-Buchholz urbanes Leben mit gr\u00fcner Erholung. Der Stadtteil wird gepr\u00e4gt von modernen Wohngebieten, idyllischen Fachwerkh\u00e4usern und dem weitl\u00e4ufigen Stadtfelddamm. Die N\u00e4he zur Medizinischen Hochschule und zahlreichen Forschungseinrichtungen macht ihn besonders attraktiv. Mit dem Hermann-L\u00f6ns-Park und der Eilenriede in unmittelbarer Umgebung bietet Gro\u00df-Buchholz viel Raum f\u00fcr Freizeit und Entspannung. Dank guter Infrastruktur und schneller Anbindung an die Innenstadt ist der Stadtteil ideal f\u00fcr alle, die stadtnah und dennoch ruhig wohnen m\u00f6chten.","dis_auswahl":"gross-buchholz"},"class_list":["post-35944","stadtteil","type-stadtteil","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/it\/wp-json\/wp\/v2\/stadtteil\/35944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/it\/wp-json\/wp\/v2\/stadtteil"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/it\/wp-json\/wp\/v2\/types\/stadtteil"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/it\/wp-json\/wp\/v2\/media?parent=35944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}