{"id":34234,"date":"2025-04-28T12:49:42","date_gmt":"2025-04-28T10:49:42","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/location\/nikolaikirche-hiddestorf\/"},"modified":"2025-10-09T11:23:36","modified_gmt":"2025-10-09T09:23:36","slug":"nikolaikirche-hiddestorf","status":"publish","type":"location","link":"https:\/\/stage.hannover-living.dev\/ja\/location\/nikolaikirche-hiddestorf\/","title":{"rendered":"\u30d2\u30c3\u30c7\u30b9\u30c8\u30eb\u30d5\u8056\u30cb\u30b3\u30e9\u30b9\u6559\u4f1a"},"template":"","meta":{"loc_subtitle":"\u00c4ltestes Bauwerk Hemmingen","loc_beschreibung":"<p>Die <strong data-start=\"278\" data-end=\"306\">Nikolaikirche Hiddestorf<\/strong> ist ein bedeutendes Zeugnis mittelalterlicher Baukunst im s\u00fcdlichen Umland von Hannover. Mit ihrer \u00fcber 800-j\u00e4hrigen Geschichte pr\u00e4gt sie das Ortsbild und ist zugleich ein Ort lebendigen Glaubens. Eingebettet in l\u00e4ndlicher Idylle bietet sie Raum f\u00fcr Gottesdienste, kulturelle Veranstaltungen und Momente der Einkehr. Ihre schlichte romanische Architektur und die pers\u00f6nliche Atmosph\u00e4re machen die Kirche zu einem besonderen Treffpunkt f\u00fcr Gemeinde und G\u00e4ste gleicherma\u00dfen.<\/p>\n<p>&nbsp;<\/p>\n","loc_strasse":"Ostertorstra\u00dfe","loc_hausnummer":"9","loc_plz":"30966","loc_ort":"Hemmingen","loc_google_maps":"Nikolaikirche Hiddestorf,Ostertorstra\u00dfe 9,30966 Hemmingen","loc_telefonnummer":"","loc_stadtteil":"region","loc_teaserbild":"42733","loc_teasertext":"Nikolaikirche Hiddestorf \/Ostertorstra\u00dfe 9, 30966 Hemmingen)\r\nBranchen\/Rubriken: Kirchen (sehenswert)","loc_webseite":"www.kirche-hiddestorf.de","loc_360_link":"","loc_facebook":"","loc_instagram":"","loc_tiktok":"","loc_speisekarte":"","loc_tischreserverierung":"","loc_art_gastro_betrieb":"false","loc_art_der_kueche":[],"loc_ambiente":"","loc_switch_google_preisklasse":"false","loc_preisklasse":"","loc_unser_tipp":"","loc_zutaten":"false","loc_trend":[],"loc_switch_open_google":"false","loc_switch_open_show":"false","loc_open_montag":"","loc_open_dienstag":"","loc_open_mittwoch":"","loc_open_donnerstag":"","loc_open_freitag":"","loc_open_samstag":"","loc_open_sontag":"","loc_nachhaltigkeit":"false","loc_galerie":[],"loc_location_art":["region","sightseeing"],"loc_nightlife":[],"loc_freizeit":["sehenswuerdigkeiten_highlights"],"loc_events_show":"false","loc_rest_show":"false","loc_crm_anrede":"","loc_crm_vorname":"","loc_crm_nachname":"","loc_crm_email":"","loc_admin_google_adress":"Nikolaikirche Hiddestorf,Ostertorstra\u00dfe 9,30966 Hemmingen","loc_admin_google_place_id":"ChIJSYjCm4yfukcRjwuR684pxY4","loc_admin_master_id":"306"},"class_list":["post-34234","location","type-location","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/ja\/wp-json\/wp\/v2\/location\/34234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/ja\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/ja\/wp-json\/wp\/v2\/types\/location"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/ja\/wp-json\/wp\/v2\/media?parent=34234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}