{"id":43522,"date":"2025-11-12T22:30:20","date_gmt":"2025-11-12T20:30:20","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/veranstaltungen\/tour-fuer-kinder-hannover-fuer-kluge-koepfe\/"},"modified":"2025-11-12T22:30:20","modified_gmt":"2025-11-12T20:30:20","slug":"tour-fuer-kinder-hannover-fuer-kluge-koepfe","status":"publish","type":"veranstaltungen","link":"https:\/\/stage.hannover-living.dev\/sv\/veranstaltungen\/tour-fuer-kinder-hannover-fuer-kluge-koepfe\/","title":{"rendered":"Rundtur f\u00f6r barn: \"Hannover f\u00f6r smarta hj\u00e4rnor\""},"author":0,"template":"","meta":{"ev_date":{"rrule":"DTSTART=19700101T000000Z","dates":[{"start":"1782991800"},{"start":"1783423800"},{"start":"1783596600"},{"start":"1784028600"},{"start":"1784201400"},{"start":"1784633400"},{"start":"1784806200"},{"start":"1785238200"},{"start":"1785411000"},{"start":"1785843000"}]},"ev_beschreibung":"<p><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Die \u201eTour f\u00fcr Kinder\u201c unter dem Titel \u201eHannover f\u00fcr kluge K\u00f6pfe\u201c bietet eine informative Stadtf\u00fchrung durch die Altstadt von Hannover.<\/span> <span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Kinder ab 8 Jahren erhalten dabei fundierte Einblicke in die Geschichte und Besonderheiten der Stadt.<\/span> <span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Die Guides vermitteln Wissen auf verst\u00e4ndliche Weise und beantworten Fragen zu historischen Ereignissen und Pers\u00f6nlichkeiten.<\/span><\/p>\n<p><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Die Tour beginnt an der Tourist-Information am Ernst-August-Platz 8 und f\u00fchrt durch die Altstadt bis zum Neuen Rathaus.<\/span> <span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">In den nieders\u00e4chsischen Oster-, Sommer- und Herbstferien findet die F\u00fchrung dienstags und donnerstags um 11:30 Uhr statt und dauert etwa 1,5 Stunden.<\/span> <span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">In dieser Zeit werden verschiedene Stationen besucht, an denen die Kinder Informationen \u00fcber die Stadtgeschichte erhalten.<\/span><\/p>\n","ev_galerie":[],"ev_ticket":"https:\/\/www.hannover-tourismus.de\/hannover-fuer-kluge-koepfe\/#\/","ev_poster":"","ev_veranstaltungsheader":"","ev_youtube":"","ev_kategorie":["stadttouren"],"ev_teaserbild":"43523","ev_teasertext":"Entdeckt Hannovers Geschichte bei der Tour f\u00fcr Kinder \u2013 dienstags und donnerstags in den Ferien.","ev_seo_name":"Tourist Information Hannover","ev_seo_strasse":"Ernst-August-Platz 8","ev_seo_plz":"30159","ev_seo_ort":"Hannover"},"class_list":["post-43522","veranstaltungen","type-veranstaltungen","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/sv\/wp-json\/wp\/v2\/veranstaltungen\/43522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/sv\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/sv\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/sv\/wp-json\/wp\/v2\/media?parent=43522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}