{"id":43785,"date":"2026-01-13T21:11:43","date_gmt":"2026-01-13T19:11:43","guid":{"rendered":"https:\/\/stage.hannover-living.dev\/veranstaltungen\/ich-sehe-was-was-du-nicht-siehst-2\/"},"modified":"2026-01-13T21:11:43","modified_gmt":"2026-01-13T19:11:43","slug":"ich-sehe-was-was-du-nicht-siehst-2","status":"publish","type":"veranstaltungen","link":"https:\/\/stage.hannover-living.dev\/tr\/veranstaltungen\/ich-sehe-was-was-du-nicht-siehst-2\/","title":{"rendered":"Ich sehe was, was du nicht siehst!"},"author":0,"template":"","meta":{"ev_date":{"rrule":"DTSTART=19700101T000000Z","dates":[]},"ev_beschreibung":"<p class=\"western\"><span style=\"font-size: 9.0pt\">Dunkel, poetisch und verst\u00f6rend sch\u00f6n: Die Bildwelten von Anke Feuchtenberger ziehen uns hinein und lassen nicht mehr los. Ihre Zeichnungen und Geschichten bewegen sich zwischen Traum und Realit\u00e4t. Sie greifen Erinnerungen und Illusion auf und entfalten dabei eine leise innere Spannung.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 9.0pt\">Feuchtenberger spielt mit weiblichen Rollenbildern, verwischt Grenzen und erschafft ambivalente Wesen aus Mensch und Tier. Die Geschichten folgen einer ganz eigenen Logik und entfalten sich wie Gedanken. Themen wie Kindheit, K\u00f6rper, Mutterschaft und das Aufwachsen in der DDR ziehen sich dabei wie ein roter Faden durch ihre Bildwelten.<\/span><\/p>\n<p class=\"western\"><span style=\"font-size: 9.0pt\">Im Zentrum der Ausstellung stehen gro\u00dfformatige Kohlezeichnungen sowie Originale aus dem vielfach ausgezeichneten Werken <em><span>Genossin Kuckuck<\/span><\/em> und <em><span>Die Hure H.<\/span><\/em>. Erg\u00e4nzt werden sie durch weitere medien\u00fcbergreifende Arbeiten wie Plakate, Siebdrucke und andere Buchprojekte.<\/span><\/p>\n","ev_galerie":[],"ev_ticket":"","ev_poster":"","ev_veranstaltungsheader":"43786","ev_youtube":"","ev_kategorie":["kunst_kultur"],"ev_teaserbild":"43786","ev_teasertext":"Anke Feuchtenberger","ev_seo_name":"Karikaturmuseum Wilhelm Busch","ev_seo_strasse":"Georgengarten 1","ev_seo_plz":"30167","ev_seo_ort":"Hannover"},"class_list":["post-43785","veranstaltungen","type-veranstaltungen","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stage.hannover-living.dev\/tr\/wp-json\/wp\/v2\/veranstaltungen\/43785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.hannover-living.dev\/tr\/wp-json\/wp\/v2\/veranstaltungen"}],"about":[{"href":"https:\/\/stage.hannover-living.dev\/tr\/wp-json\/wp\/v2\/types\/veranstaltungen"}],"wp:attachment":[{"href":"https:\/\/stage.hannover-living.dev\/tr\/wp-json\/wp\/v2\/media?parent=43785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}